{"id":2811,"date":"2023-01-07T19:33:19","date_gmt":"2023-01-07T17:33:19","guid":{"rendered":"https:\/\/leserre.co\/it\/?page_id=2811"},"modified":"2024-10-24T10:26:17","modified_gmt":"2024-10-24T08:26:17","slug":"contatti","status":"publish","type":"page","link":"https:\/\/zeroidee.com\/contatti\/","title":{"rendered":"Contatti"},"content":{"rendered":"<h1><a href=\"https:\/\/leserre.co\"><\/p>\n<div style=\"font-size: 250px; line-height: 0.9;letter-spacing:-6px;\">LE(SERRE<\/div>\n<p><\/a><\/h1>\n<h1>\n<div style=\"font-size: 70px;letter-spacing:-4px;\">LE(SERRE<\/div>\n<\/h1>\n<h4>\n<p style=\"font-weight: 400; letter-spacing: 0px; line-height: 38px; color: #000000; text-align: left; font-size: 34px;\">Vieni a trovarci in Strada dell&#8217;Artigiano 26,\u00a0Campoformido\u00a0<br \/>&#8211; Udine<\/p>\n<\/h4>\n<h5>\n<p style=\"color:#000;letter-spacing:0px;line-height:28px;margin:0;padding:0;font-size:26px;\">Puoi scriverci a <u><a href=\"mailto:info@leserre.co\">info@leserre.co<\/a><\/u><\/p>\n<p style=\"color:#000;letter-spacing:0.5px;line-height:25px;margin:14px 0 0 0;padding:0;font-size:22px;\">\n    <a href=\"mailto:joseph@leserre.co\">joseph@leserre.co<\/a><br \/>\n    <a href=\"mailto:laura@leserre.co\">laura@leserre.co<\/a><br \/>\n    <a href=\"mailto:matteo@leserre.co\">matteo@leserre.co<\/a><br \/>\n    <a href=\"mailto:giovanni@leserre.co\">giovanni@leserre.co<\/a><br \/>\n    <a href=\"mailto:francesco@leserre.co\">francesco@leserre.co<\/a>\n<\/p>\n<\/h5>\n<h4>\n<p style=\"font-weight: 400; letter-spacing: 0px; line-height: 30px; color: #000000; text-align: left;font-size:28px;\">Puoi venire a trovarci in Strada dell&#8217;Artigiano 26, Basaldella, Campoformido<br \/>&#8211; Udine<\/p>\n<\/h4>\n<h5>\n<p style=\"color:#000;letter-spacing:0px;line-height:26px;margin:0;padding:0;font-size:24px;\">Puoi scriverci a <u><a href=\"mailto:info@leserre.co\">info@leserre.co<\/a><\/u><\/p>\n<p style=\"color:#000;letter-spacing:0.5px;line-height:23px;margin:10px 0 0 0;padding:0;font-size:20px;\">\n    <a href=\"mailto:joseph@leserre.co\">joseph@leserre.co<\/a><br \/>\n    <a href=\"mailto:laura@leserre.co\">laura@leserre.co<\/a><br \/>\n    <a href=\"mailto:matteo@leserre.co\">matteo@leserre.co<\/a><br \/>\n    <a href=\"mailto:giovanni@leserre.co\">giovanni@leserre.co<\/a><br \/>\n    <a href=\"mailto:francesco@leserre.co\">francesco@leserre.co<\/a>\n<\/p>\n<\/h5>\n<div>\n<p style=\"color: #000; letter-spacing: 0.3px; line-height: 22px; margin: 0; padding: 0; font-size: 18px;\">Informazioni<\/p>\n<p>Puntozero Societ\u00e0 Cooperativa<br \/>Sede legale Via Liguria 275, 33100 Udine<br \/>C.F. e PI 02661810305<br \/><a href=\"mailto:info@cooperativapuntozero.it\">info@cooperativapuntozero.it<\/a><br \/><a href=\"mailto:amministrazione@cooperativapuntozero.it\">amministrazione@cooperativapuntozero.it<\/a><\/p>\n<p>Zeroidee A.P.S.<br \/>Sede legale Strada delle Betulle 21\/12, Campoformido Udine<br \/>C.F. 94150160300<br \/><a href=\"mailto:info@zeroidee.com\">info@zeroidee.com<\/a><br \/><a href=\"mailto:amministrazione@zeroidee.com\">amministrazione@zeroidee.com<\/a><\/p>\n<p>Associazione culturale Altrememorie<br \/>Sede legale Via Buia 22, 33100 Udine<br \/>C.F. 94109750300<br \/><a href=\"mailto:info@altrememorie.it\">info@altrememorie.it<\/a><br \/><a href=\"mailto:amministrazione@altrememorie.it\">amministrazione@altrememorie.it<\/a><\/p>\n<p>Soluzioni S.R.L.S.<br \/>Sede legale Strada delle Betulle 21\/12, Campoformido Udine<br \/>Capitale sociale i.v. 1.500,00<br \/>C.F. e PI 02836860300<br \/>Numero REA: 291851<br \/>info@soluzionilab.it<br \/>amministrazione@soluzionilab.it<\/p>\n<\/div>\n<div>\n<p style=\"color:#000;letter-spacing:0.3px;line-height:20px;margin:0;padding:0;font-size:16px;\">Informazioni<\/p>\n<p>Puntozero Societ\u00e0 Cooperativa<br \/>\nSede legale Via Liguria 275, 33100 Udine<br \/>\nCF e PI 02661810305<br \/>\n<a href=\"mailto:info@cooperativapuntozero.it\">info@cooperativapuntozero.it<\/a><br \/>\n<a href=\"mailto:amministrazione@cooperativapuntozero.it\">amministrazione@cooperativapuntozero.it<\/a><\/p>\n<p>Zeroidee A.P.S.<br \/>\nSede legale Strada delle Betulle 21\/12, Campoformido Udine<br \/>\nC.F. 94150160300<br \/>\n<a href=\"mailto:info@zeroidee.com\">info@zeroidee.com<\/a><br \/>\n<a href=\"mailto:amministrazione@zeroidee.com\">amministrazione@zeroidee.com<\/a><\/p>\n<p>Associazione culturale Altrememorie<br \/>\nSede legale Via Buia 22, 33100 Udine<br \/>\nC.F. 94109750300<br \/>\n<a href=\"mailto:info@altrememorie.it\">info@altrememorie.it<\/a><br \/>\n<a href=\"mailto:amministrazione@altrememorie.it\">amministrazione@altrememorie.it<\/a><\/p>\n<p>Soluzioni S.R.L.S.<br \/>\nSede legale Strada delle Betulle 21\/12, Campoformido Udine<br \/>\nCapitale sociale i.v. 1.500,00<br \/>\nCF e PI 02836860300<br \/>\nNumero REA: 291851<br \/>\n<a href=\"mailto:info@soluzioni\">info@soluzioni<\/a><br \/>\n<a href=\"mailto:amministrazione@soluzioni\">amministrazione@soluzioni<\/a><\/p>\n<\/div>\n<p><!--more--><br \/>\n<!-- {\"name\":\"TestContatti07gen2023\",\"type\":\"layout\",\"children\":[{\"type\":\"section\",\"props\":{\"style\":\"default\",\"width\":\"expand\",\"vertical_align\":\"middle\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"title_breakpoint\":\"xl\",\"image_position\":\"center-center\",\"padding\":\"small\",\"class\":\"col252525 bgF4F1E2 pyROWS\",\"padding_remove_top\":true},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"position_sticky_breakpoint\":\"m\",\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\"},\"children\":[{\"type\":\"image\",\"props\":{\"margin\":\"default\",\"image_svg_color\":\"emphasis\",\"image\":\"\\\/wp-content\\\/themes\\\/webdev-theme\\\/websvg\\\/header-logo-leserre.svg\",\"class\":\"pagContattiLogo\",\"link\":\"https:\\\/\\\/leserre.co\\\/\",\"status\":\"disabled\"},\"name\":\"LOGO DESKTOP\\\/MOBILE\"},{\"type\":\"headline\",\"props\":{\"title_element\":\"h1\",\"content\":\"\n\n<div style=\\\"font-size: 250px; line-height: 0.9;letter-spacing:-6px;\\\">LE(SERRE<\\\/div>\",\"visibility\":\"s\",\"link\":\"https:\\\/\\\/leserre.co\",\"class\":\"col000000\"}},{\"type\":\"headline\",\"props\":{\"title_element\":\"h1\",\"content\":\"\n\n<div style=\\\"font-size: 70px;letter-spacing:-4px;\\\">LE(SERRE<\\\/div>\",\"visibility\":\"hidden-s\",\"margin\":\"small\",\"class\":\"col000000\"}}]}],\"props\":{\"margin\":\"remove-vertical\"}}],\"name\":\"FASCIA GIALLA\"},{\"type\":\"section\",\"props\":{\"style\":\"default\",\"width\":\"expand\",\"vertical_align\":\"middle\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"title_breakpoint\":\"xl\",\"image_position\":\"center-center\",\"padding\":\"small\",\"class\":\"col252525 bgF4F1E2 pyROWS\",\"padding_remove_top\":true},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"position_sticky_breakpoint\":\"m\",\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\"},\"children\":[{\"type\":\"headline\",\"props\":{\"title_element\":\"h4\",\"content\":\"\n\n<p style=\\\"font-weight: 400; letter-spacing: 0px; line-height: 38px; color: #000000; text-align: left; font-size: 34px;\\\">Vieni a trovarci in Strada dell'Artigiano 26,\\u00a0Campoformido\\u00a0<br \\\/>- Udine<\\\/p>\",\"class\":\"fontWe500 fontBold col000000\",\"content_en_us\":\"We like to realise ideas for ourselves and for others, tell stories, weave relationships. We are a non-profit organisation based in the Municipality of Udine, active since 2011 as an incorporated organisation and since 2008 as a working group. We actively participate in the promotion of numerous national and international cultural projects, aimed at spreading through art and creativity an idea of participation in the social life of the city.\",\"margin\":\"default\",\"margin_remove_top\":true,\"visibility\":\"s\",\"content_en_gb\":\"\n\n<p style=\\\"font-weight: 400; letter-spacing: 0px; line-height: 38px; color: #000000; text-align: left; font-size: 34px;\\\">Come and visit us at Strada dell'Artigiano 26, Campoformido, Udine<br \\\/>- Udine<\\\/p>\"},\"name\":\"LOCATION DESKTOP\"},{\"type\":\"headline\",\"props\":{\"title_element\":\"h5\",\"content\":\"\n\n<p style=\\\"color:#000;letter-spacing:0px;line-height:28px;margin:0;padding:0;font-size:26px;\\\">Puoi scriverci a <u><a href=\\\"mailto:info@leserre.co\\\">info@leserre.co<\\\/a><\\\/u><\\\/p>\\n\n\n<p style=\\\"color:#000;letter-spacing:0.5px;line-height:25px;margin:14px 0 0 0;padding:0;font-size:22px;\\\">\\n    <a href=\\\"mailto:joseph@leserre.co\\\">joseph@leserre.co<\\\/a><br \/>\\n    <a href=\\\"mailto:laura@leserre.co\\\">laura@leserre.co<\\\/a><br \/>\\n    <a href=\\\"mailto:matteo@leserre.co\\\">matteo@leserre.co<\\\/a><br \/>\\n    <a href=\\\"mailto:giovanni@leserre.co\\\">giovanni@leserre.co<\\\/a><br \/>\\n    <a href=\\\"mailto:francesco@leserre.co\\\">francesco@leserre.co<\\\/a>\\n<\\\/p>\",\"class\":\"fontWe500 pagContattiContent mbReset col000000\",\"content_en_us\":\"We are five partners (Francesco, Giovanni, Laura, Matteo and Joseph) and we have decided to invest in a common entrepreneurial project, promoting the challenge of relationships and cooperation by extending it to many other professionals who, like us, work in the cultural and creative field. The projects we deal with are of different kinds: conception, development and management of cultural projects, festivals, art exhibitions; video productions; photography; installations, furnishing of urban or natural spaces; workshops and laboratories. In all of them we use creativity as a generator of social and cultural innovation. We work with private and public bodies and collaborate with national and international partners.\",\"visibility\":\"s\",\"content_en_gb\":\"\n\n<p style=\\\"color:#000;letter-spacing:0px;line-height:28px;margin:0;padding:0;font-size:26px;\\\">Write to us at <u><a href=\\\"mailto:info@leserre.co\\\">info@leserre.co<\\\/a><\\\/u><\\\/p>\\n\n\n<p style=\\\"color:#000;letter-spacing:0.5px;line-height:25px;margin:14px 0 0 0;padding:0;font-size:22px;\\\">\\n    <a href=\\\"mailto:joseph@leserre.co\\\">joseph@leserre.co<\\\/a><br \/>\\n    <a href=\\\"mailto:laura@leserre.co\\\">laura@leserre.co<\\\/a><br \/>\\n    <a href=\\\"mailto:matteo@leserre.co\\\">matteo@leserre.co<\\\/a><br \/>\\n    <a href=\\\"mailto:giovanni@leserre.co\\\">giovanni@leserre.co<\\\/a><br \/>\\n    <a href=\\\"mailto:francesco@leserre.co\\\">francesco@leserre.co<\\\/a>\\n<\\\/p>\"},\"name\":\"CONTATTI DESKTOP\"},{\"type\":\"headline\",\"props\":{\"title_element\":\"h4\",\"content\":\"\n\n<p style=\\\"font-weight: 400; letter-spacing: 0px; line-height: 30px; color: #000000; text-align: left;font-size:28px;\\\">Puoi venire a trovarci in Strada dell'Artigiano 26, Basaldella, Campoformido<br \/>- Udine<\\\/p>\",\"class\":\"fontWe500 mtReset col000000\",\"content_en_us\":\"We like to realise ideas for ourselves and for others, tell stories, weave relationships. We are a non-profit organisation based in the Municipality of Udine, active since 2011 as an incorporated organisation and since 2008 as a working group. We actively participate in the promotion of numerous national and international cultural projects, aimed at spreading through art and creativity an idea of participation in the social life of the city.\",\"margin\":\"default\",\"margin_remove_top\":false,\"visibility\":\"hidden-s\",\"content_en_gb\":\"\n\n<p style=\\\"font-weight: 400; letter-spacing: 0px; line-height: 30px; color: #000000; text-align: left;font-size:28px;\\\">Come and visit us at Strada dell'Artigiano 26, Campoformido, Udine<\\\/p>\"},\"name\":\"LOCATION MOBILE\"},{\"type\":\"headline\",\"props\":{\"title_element\":\"h5\",\"content\":\"\n\n<p style=\\\"color:#000;letter-spacing:0px;line-height:26px;margin:0;padding:0;font-size:24px;\\\">Puoi scriverci a <u><a href=\\\"mailto:info@leserre.co\\\">info@leserre.co<\\\/a><\\\/u><\\\/p>\\n\n\n<p style=\\\"color:#000;letter-spacing:0.5px;line-height:23px;margin:10px 0 0 0;padding:0;font-size:20px;\\\">\\n    <a href=\\\"mailto:joseph@leserre.co\\\">joseph@leserre.co<\\\/a><br \/>\\n    <a href=\\\"mailto:laura@leserre.co\\\">laura@leserre.co<\\\/a><br \/>\\n    <a href=\\\"mailto:matteo@leserre.co\\\">matteo@leserre.co<\\\/a><br \/>\\n    <a href=\\\"mailto:giovanni@leserre.co\\\">giovanni@leserre.co<\\\/a><br \/>\\n    <a href=\\\"mailto:francesco@leserre.co\\\">francesco@leserre.co<\\\/a>\\n<\\\/p>\",\"class\":\"fontWe500 ptReset pagContattiContent mtReset col000000\",\"content_en_us\":\"We are five partners (Francesco, Giovanni, Laura, Matteo and Joseph) and we have decided to invest in a common entrepreneurial project, promoting the challenge of relationships and cooperation by extending it to many other professionals who, like us, work in the cultural and creative field. The projects we deal with are of different kinds: conception, development and management of cultural projects, festivals, art exhibitions; video productions; photography; installations, furnishing of urban or natural spaces; workshops and laboratories. In all of them we use creativity as a generator of social and cultural innovation. We work with private and public bodies and collaborate with national and international partners.\",\"visibility\":\"hidden-s\",\"content_en_gb\":\"\n\n<p style=\\\"color:#000;letter-spacing:0px;line-height:26px;margin:0;padding:0;font-size:24px;\\\">Write to us at <u><a href=\\\"mailto:info@leserre.co\\\">info@leserre.co<\\\/a><\\\/u><\\\/p>\\n\n\n<p style=\\\"color:#000;letter-spacing:0.5px;line-height:23px;margin:10px 0 0 0;padding:0;font-size:20px;\\\">\\n    <a href=\\\"mailto:joseph@leserre.co\\\">joseph@leserre.co<\\\/a><br \/>\\n    <a href=\\\"mailto:laura@leserre.co\\\">laura@leserre.co<\\\/a><br \/>\\n    <a href=\\\"mailto:matteo@leserre.co\\\">matteo@leserre.co<\\\/a><br \/>\\n    <a href=\\\"mailto:giovanni@leserre.co\\\">giovanni@leserre.co<\\\/a><br \/>\\n    <a href=\\\"mailto:francesco@leserre.co\\\">francesco@leserre.co<\\\/a>\\n<\\\/p>\"},\"name\":\"CONTATTI MOBILE\"}]}],\"props\":{\"margin\":\"remove-vertical\"}}],\"name\":\"FASCIA GIALLA\"},{\"type\":\"section\",\"props\":{\"style\":\"default\",\"width\":\"expand\",\"vertical_align\":\"middle\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"title_breakpoint\":\"xl\",\"image_position\":\"center-center\",\"padding\":\"none\",\"class\":\"pyROWS\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"position_sticky_breakpoint\":\"m\",\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"class\":\"pbReset mbReset\"},\"children\":[{\"type\":\"text\",\"props\":{\"margin\":\"default\",\"column_breakpoint\":\"m\",\"class\":\"pagContattiContent mbReset pbReset col000000\",\"content\":\"\n\n<p style=\\\"color: #000; letter-spacing: 0.3px; line-height: 22px; margin: 0; padding: 0; font-size: 18px;\\\">Informazioni<br \\\/><br \\\/>Puntozero Societ\\u00e0 Cooperativa<br \\\/>Sede legale Via Liguria 275, 33100 Udine<br \\\/>C.F. e PI 02661810305<br \\\/><a href=\\\"mailto:info@cooperativapuntozero.it\\\">info@cooperativapuntozero.it<\\\/a><br \\\/><a href=\\\"mailto:amministrazione@cooperativapuntozero.it\\\">amministrazione@cooperativapuntozero.it<\\\/a><br \\\/><br \\\/>Zeroidee A.P.S.<br \\\/>Sede legale Strada delle Betulle 21\\\/12, Campoformido Udine<br \\\/>C.F. 94150160300<br \\\/><a href=\\\"mailto:info@zeroidee.com\\\">info@zeroidee.com<\\\/a><br \\\/><a href=\\\"mailto:amministrazione@zeroidee.com\\\">amministrazione@zeroidee.com<\\\/a><br \\\/><br \\\/>Associazione culturale Altrememorie<br \\\/>Sede legale Via Buia 22, 33100 Udine<br \\\/>C.F. 94109750300<br \\\/><a href=\\\"mailto:info@altrememorie.it\\\">info@altrememorie.it<\\\/a><br \\\/><a href=\\\"mailto:amministrazione@altrememorie.it\\\">amministrazione@altrememorie.it<\\\/a><br \\\/><br \\\/>Soluzioni S.R.L.S.<br \\\/>Sede legale Strada delle Betulle 21\\\/12, Campoformido Udine<br \\\/>Capitale sociale i.v. 1.500,00<br \\\/>C.F. e PI 02836860300<br \\\/>Numero REA: 291851<br \\\/>info@soluzionilab.it<br \\\/>amministrazione@soluzionilab.it<\\\/p>\",\"visibility\":\"s\",\"content_en_gb\":\"\n\n<p style=\\\"color: #000; letter-spacing: 0.3px; line-height: 22px; margin: 0; padding: 0; font-size: 18px;\\\">About<br \\\/><br \\\/>Puntozero Societ\\u00e0 Cooperativa <br \\\/>Registered office: Via Liguria 275, 33100 Udine<br \\\/>Tax code and VAT number: 02661810305 <br \\\/><a href=\\\"mailto:info@cooperativapuntozero.it\\\">info@cooperativapuntozero.it<\\\/a><br \\\/><a href=\\\"mailto:amministrazione@cooperativapuntozero.it\\\">amministrazione@cooperativapuntozero.it<\\\/a><br \\\/><br \\\/>Zeroidee A.P.S.<br \\\/>Registered office: Strada delle Betulle 21\\\/12, Campoformido, Udine <br \\\/>Tax code: 94150160300 <br \\\/><a href=\\\"mailto:info@zeroidee.com\\\">info@zeroidee.com<\\\/a><br \\\/><a href=\\\"mailto:amministrazione@zeroidee.com\\\">amministrazione@zeroidee.com<\\\/a><br \\\/><br \\\/>Associazione culturale Altrememorie<br \\\/>Registered office: Via Buia 22, 33100 Udine <br \\\/>Tax code: 94109750300 <br \\\/><a href=\\\"mailto:info@altrememorie.it\\\">info@altrememorie.it<\\\/a><br \\\/><a href=\\\"mailto:amministrazione@altrememorie.it\\\">amministrazione@altrememorie.it<\\\/a><br \\\/><br \\\/>Soluzioni S.R.L.S.<br \\\/>Registered office: Strada delle Betulle 21\\\/12, Campoformido, Udine <br \\\/>Share capital, fully paid-up: 1,500.00 \\u20ac <br \\\/>Tax code and VAT number: 02836860300 <br \\\/>Economic and Administrative Index No.: 291851 <br \\\/><a href=\\\"mailto:info@soluzioni\\\">info@soluzioni<\\\/a><br \\\/><a href=\\\"mailto:amministrazione@soluzioni\\\">amministrazione@soluzioni<\\\/a><\\\/p>\"},\"name\":\"INFORMAZIONI DESKTOP\"},{\"type\":\"text\",\"props\":{\"margin\":\"default\",\"column_breakpoint\":\"m\",\"class\":\"pagContattiContent mbReset pbReset mtReset mbReset col000000\",\"content\":\"\n\n<p style=\\\"color:#000;letter-spacing:0.3px;line-height:20px;margin:0;padding:0;font-size:16px;\\\">Informazioni\n\n\\nPuntozero Societ\\u00e0 Cooperativa<br \/>\\nSede legale Via Liguria 275, 33100 Udine<br \/>\\nCF e PI 02661810305<br \/>\\n<a href=\\\"mailto:info@cooperativapuntozero.it\\\">info@cooperativapuntozero.it<\\\/a><br \/>\\n<a href=\\\"mailto:amministrazione@cooperativapuntozero.it\\\">amministrazione@cooperativapuntozero.it<\\\/a>\n\n\\n\\nZeroidee A.P.S.<br \/>\\nSede legale Strada delle Betulle 21\\\/12, Campoformido Udine<br \/>\\nC.F. 94150160300<br \/>\\n<a href=\\\"mailto:info@zeroidee.com\\\">info@zeroidee.com<\\\/a><br \/>\\n<a href=\\\"mailto:amministrazione@zeroidee.com\\\">amministrazione@zeroidee.com<\\\/a>\n\n\\n\\nAssociazione culturale Altrememorie<br \/>\\nSede legale Via Buia 22, 33100 Udine<br \/>\\nC.F. 94109750300<br \/>\\n<a href=\\\"mailto:info@altrememorie.it\\\">info@altrememorie.it<\\\/a><br \/>\\n<a href=\\\"mailto:amministrazione@altrememorie.it\\\">amministrazione@altrememorie.it<\\\/a>\n\n\\n\\nSoluzioni S.R.L.S.<br \/>\\nSede legale Strada delle Betulle 21\\\/12, Campoformido Udine<br \/>\\nCapitale sociale i.v. 1.500,00<br \/>\\nCF e PI 02836860300<br \/>\\nNumero REA: 291851<br \/>\\n<a href=\\\"mailto:info@soluzioni\\\">info@soluzioni<\\\/a><br \/>\\n<a href=\\\"mailto:amministrazione@soluzioni\\\">amministrazione@soluzioni<\\\/a><\\\/p>\",\"visibility\":\"hidden-s\",\"content_en_gb\":\"\n\n<p style=\\\"color: #000; letter-spacing: 0.3px; line-height: 20px; margin: 0; padding: 0; font-size: 16px;\\\">About<br \\\/><br \\\/>Puntozero Societ\\u00e0 Cooperativa<br \\\/>Registered office: Via Liguria 275, 33100 Udine <br \\\/>Tax code and VAT number: 02661810305 <br \\\/><a href=\\\"mailto:info@cooperativapuntozero.it\\\">info@cooperativapuntozero.it<\\\/a><br \\\/><a href=\\\"mailto:amministrazione@cooperativapuntozero.it\\\">amministrazione@cooperativapuntozero.it<\\\/a><br \\\/><br \\\/>Zeroidee A.P.S.<br \\\/>Registered office: Strada delle Betulle 21\\\/12, Campoformido, Udine <br \\\/>Tax code: 94150160300 <br \\\/><a href=\\\"mailto:info@zeroidee.com\\\">info@zeroidee.com<\\\/a><br \\\/><a href=\\\"mailto:amministrazione@zeroidee.com\\\">amministrazione@zeroidee.com<\\\/a><br \\\/><br \\\/>Associazione culturale Altrememorie<br \\\/>Registered office: Via Buia 22, 33100 Udine <br \\\/>Tax code: 94109750300 <br \\\/><a href=\\\"mailto:info@altrememorie.it\\\">info@altrememorie.it<\\\/a><br \\\/><a href=\\\"mailto:amministrazione@altrememorie.it\\\">amministrazione@altrememorie.it<\\\/a><br \\\/><br \\\/>Soluzioni S.R.L.S.<br \\\/>Registered office: Strada delle Betulle 21\\\/12, Campoformido, Udine <br \\\/>Share capital, fully paid-up: 1,500.00 \\u20ac <br \\\/>Tax code and VAT number: 02836860300 <br \\\/><a href=\\\"mailto:info@soluzioni\\\">info@soluzioni<\\\/a><br \\\/><a href=\\\"mailto:amministrazione@soluzioni\\\">amministrazione@soluzioni<\\\/a><\\\/p>\"},\"name\":\"INFORMAZIONI MOBILE\"}]}],\"props\":{\"column_gap\":\"collapse\",\"row_gap\":\"collapse\"}}],\"name\":\"FASCIA BIANCA\"}],\"version\":\"2.7.21\"} --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LE(SERRE LE(SERRE Vieni a trovarci in Strada dell&#8217;Artigiano 26,\u00a0Campoformido\u00a0&#8211; Udine Puoi scriverci a info@leserre.co joseph@leserre.co laura@leserre.co matteo@leserre.co giovanni@leserre.co francesco@leserre.co Puoi venire a trovarci in Strada dell&#8217;Artigiano 26, Basaldella, Campoformido&#8211; Udine Puoi scriverci a info@leserre.co joseph@leserre.co laura@leserre.co matteo@leserre.co giovanni@leserre.co francesco@leserre.co Informazioni Puntozero Societ\u00e0 CooperativaSede legale Via Liguria 275, 33100 UdineC.F. e PI 02661810305info@cooperativapuntozero.itamministrazione@cooperativapuntozero.it Zeroidee A.P.S.Sede legale [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/zeroidee.com\/wp-json\/wp\/v2\/pages\/2811"}],"collection":[{"href":"https:\/\/zeroidee.com\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/zeroidee.com\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/zeroidee.com\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zeroidee.com\/wp-json\/wp\/v2\/comments?post=2811"}],"version-history":[{"count":98,"href":"https:\/\/zeroidee.com\/wp-json\/wp\/v2\/pages\/2811\/revisions"}],"predecessor-version":[{"id":4027,"href":"https:\/\/zeroidee.com\/wp-json\/wp\/v2\/pages\/2811\/revisions\/4027"}],"wp:attachment":[{"href":"https:\/\/zeroidee.com\/wp-json\/wp\/v2\/media?parent=2811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}